{"id":3277,"date":"2020-09-09T05:32:45","date_gmt":"2020-09-09T05:32:45","guid":{"rendered":"http:\/\/www.sonalikainternational.in\/Website\/?page_id=3277"},"modified":"2024-07-04T09:42:46","modified_gmt":"2024-07-04T09:42:46","slug":"become-a-dealer","status":"publish","type":"page","link":"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/","title":{"rendered":"Become A Dealer"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;21px&#8221; box_shadow_blur=&#8221;21px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.8)&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/international.sonalika.com\/wp-content\/uploads\/2020\/08\/career-banner.jpg&#8221; title_text=&#8221;career-banner&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Become-Dealer &#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;40px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;27px&#8221; box_shadow_color=&#8221;rgba(2,2,2,0.7)&#8221;][et_pb_row _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|700||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#034ea1&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; custom_css_before=&#8221;content: %22%22;|| display: block;|| width: 30%;|| height: 2px;|| background: #034ea1;|| left: 0;|| top: 30%;|| position: absolute;&#8221; custom_css_after=&#8221;content: %22%22;|| display: block;|| width: 30%;|| height: 2px;|| background: #034ea1;|| right: 0;|| top: 30%;|| position: absolute;&#8221;]<\/p>\n<h2>Become A Dealer<\/h2>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|700||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#034ea1&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221;]<\/p>\n<h2>Become A Dealer<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#222&#8243; header_2_font=&#8221;|600||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#222222&#8243; header_2_font_size=&#8221;21px&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<h2>Grow with the global leader<\/h2>\n<p>As a Sonalika dealer, you\u2019ll be putting your business name next to a world leader. Admired for its legendary Quality, Durability and Reliability (QDR), Sonalika (Brand of International Tractors Limited) has always advanced the standard in tractor automobile technology.<\/p>\n<p>Each tractor &amp; farming implement is designed to delight customers with a unique strength, pioneering performance and after sales support to deliver the best farming experience.[\/et_pb_text][et_pb_text _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#222&#8243; header_2_font=&#8221;|600||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#222222&#8243; header_2_font_size=&#8221;21px&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<h2>Partner with one of the leading tractor manufacturers in the world<br \/>\nWhat you need?<\/h2>\n<p>If you have a passion for tractor industry and are ready to invest, this is your perfect opportunity to join the growing Sonalika family. For queries, fill in inquiry form and you will be contacted by our team to discuss further association.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Form-Section&#8221; _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e8e8e8&#8243; custom_padding=&#8221;||||false|false&#8221;][et_pb_row _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#ffffff&#8221; custom_css_main_element=&#8221;background:#034ea1;||padding-top:10px;&#8221;]<\/p>\n<h2>Information<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.5.6&#8243; _module_preset=&#8221;default&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3302-o1\" lang=\"en\" dir=\"ltr\" data-wpcf7-id=\"3302\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/morocco\/wp-json\/wp\/v2\/pages\/3277#wpcf7-f3302-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3302\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3302-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:3302,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;notice_dismissed_install-cf7&quot;:true,&quot;notice_dismissed_update-cf7-5.4.2&quot;:true,&quot;notice_dismissed_rollback-cf7-5.9.6&quot;:true}}\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<style>\n::-webkit-input-placeholder { \/* Chrome\/Opera\/Safari *\/\n color: #fff;\n font-size:16px;\n}\n::-moz-placeholder { \/* Firefox 19+ *\/\n color: #fff;\n font-size:16px;\n}\n:-ms-input-placeholder { \/* IE 10+ *\/\n color: #fff;\n font-size:16px;\n}\n:-moz-placeholder { \/* Firefox 18- *\/\n color: #fff;\n font-size:16px;\n}\n.left-clm {\n width: 47%;\n position: relative;\n height: 44px;\n margin-bottom: 25px;\n background: #e8e8e8;\n float: left;\n}\n.right-clm {\n width: 47%;\n position: relative;\n height: 44px;\n margin-bottom: 25px;\n background: #e8e8e8;\n float: right;\n}\ninput[type=text]{\n background-color: #034ea1;\n border: 1px solid #034ea1;\n padding: 7px;\n color: #fff;\n width: 100%;\n font-size:16px;\n margin-bottom:0px;\n height: 44px;\n}\ninput[type=text]:focus{\n background-color: #034ea1;\n border: 1px solid #034ea1;\n padding: 7px;\n color: #fff;\n width: 100%;\n font-size:16px;\n margin-bottom: 0px;\n height: 44px;\n}\ninput[type=email]{\n background-color: #034ea1;\n border: 1px solid #034ea1;\n padding: 7px;\n color: #fff;\n font-size:16px;\n width: 100%;\n margin-bottom: 0px;\n height: 44px;\n}\ninput[type=email]:focus{\n background-color: #034ea1;\n border: 1px solid #034ea1;\n padding: 2px;\n color: #fff;\n font-size:16px;\n width: 100%;\n margin-bottom: 0px;\n height: 44px;\n}\n#dlr-cmp {\n width: 100%;\n}\nselect {\n background-color: #034ea1;\n border: 1px solid #bbb;\n padding: 2px;\n color: #fff;\n font-size:16px;\n height: 44px;\n}\nselect:focus {\n background-color: #034ea1;\n border: 1px solid #bbb;\n padding: 2px;\n color: #fff;\n font-size:16px;\n height: 44px;\n}\n#sub-button {\n background:#222;\n border: solid 2px #222;\n padding: 5px 27px 5px 27px;\n font-size: 16px;\n font-weight: 600;\n color:#fff;\n border-radius: 15px;\n cursor: pointer;\n margin-top:70px;\n}\n.wpcf7-response-output {\n display: contents;\n}\n@media only screen and (max-width: 768px) {\n .left-clm {\n width: 100% !important;\n float: left;\n }\n .right-clm {\n width: 100% !important;\n float: left;\n }\n}\n.clearfix {\n display:block;\n}\n<\/style>\n<div class=\"clearfix\">\n\t<div class=\"left-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dealer-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required left-clm\" id=\"dlr-cmp\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Full Name*\" value=\"\" type=\"text\" name=\"dealer-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"right-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dealer-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email right-clm\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Email*\" value=\"\" type=\"email\" name=\"dealer-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"left-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dealer-no\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required left-clm\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Mobile Number*\" value=\"\" type=\"text\" name=\"dealer-no\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"right-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dealer-country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required right-clm\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Country*\" value=\"\" type=\"text\" name=\"dealer-country\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"left-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dealer-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required left-clm\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Company Name*\" value=\"\" type=\"text\" name=\"dealer-company\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"right-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dealer-address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required right-clm\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Address*\" value=\"\" type=\"text\" name=\"dealer-address\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"left-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dealer-product\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required left-clm\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Product Sold*\" value=\"\" type=\"text\" name=\"dealer-product\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"right-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"select-year\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"select-year\"><option value=\"Select Number of Years in Business*\">Select Number of Years in Business*<\/option><option value=\"0-2 years\">0-2 years<\/option><option value=\"4-6 years\">4-6 years<\/option><option value=\"8-10 years\">8-10 years<\/option><option value=\"10 years\">10 years<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"right-clm\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-term\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-term\" value=\"1\" class=\"accpt\" id=\"accpt\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I've read and accept the terms & conditions<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"right-clm\">\n\t<span class=\"wpcf7-form-control-wrap recaptcha\" data-name=\"recaptcha\"><span data-sitekey=\"6LfbioMfAAAAAMhkTF3D0VfK1ZDj1zaGAw-n43Ni\" class=\"wpcf7-form-control wpcf7-recaptcha g-recaptcha\"><\/span>\r\n<noscript>\r\n\t<div class=\"grecaptcha-noscript\">\r\n\t\t<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/recaptcha\/api\/fallback?k=6LfbioMfAAAAAMhkTF3D0VfK1ZDj1zaGAw-n43Ni\" frameborder=\"0\" scrolling=\"no\" width=\"310\" height=\"430\">\r\n\t\t<\/iframe>\r\n\t\t<textarea name=\"g-recaptcha-response\" rows=\"3\" cols=\"40\" placeholder=\"reCaptcha Response Here\">\r\n\t\t<\/textarea>\r\n\t<\/div>\r\n<\/noscript>\r\n<\/span>\n\t<\/div>\n\t<div>\n\t\t<center>\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner sub-btn\" id=\"sub-button\" type=\"submit\" value=\"Submit\" \/>\n\t\t\t<\/p>\n\t\t<\/center>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Become A DealerBecome A DealerGrow with the global leader As a Sonalika dealer, you\u2019ll be putting your business name next to a world leader. Admired for its legendary Quality, Durability and Reliability (QDR), Sonalika (Brand of International Tractors Limited) has always advanced the standard in tractor automobile technology. Each tractor &amp; farming implement is designed [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-3277","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Become a Sonalika Dealer in Morocco | Join Now!<\/title>\n<meta name=\"description\" content=\"Join Sonalika as a dealer in Morocco. Partner with us to distribute high-quality agricultural equipment. Apply now!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Become a Sonalika Dealer in Morocco | Join Now!\" \/>\n<meta property=\"og:description\" content=\"Join Sonalika as a dealer in Morocco. Partner with us to distribute high-quality agricultural equipment. Apply now!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/\" \/>\n<meta property=\"og:site_name\" content=\"Sonalika Morocco\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-04T09:42:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/\",\"url\":\"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/\",\"name\":\"Become a Sonalika Dealer in Morocco | Join Now!\",\"isPartOf\":{\"@id\":\"http:\/\/international.sonalika.com\/morocco\/#website\"},\"datePublished\":\"2020-09-09T05:32:45+00:00\",\"dateModified\":\"2024-07-04T09:42:46+00:00\",\"description\":\"Join Sonalika as a dealer in Morocco. Partner with us to distribute high-quality agricultural equipment. Apply now!\",\"breadcrumb\":{\"@id\":\"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/international.sonalika.com\/morocco\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Become A Dealer\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/international.sonalika.com\/morocco\/#website\",\"url\":\"http:\/\/international.sonalika.com\/morocco\/\",\"name\":\"Sonalika Morocco\",\"description\":\"Tractor Portal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/international.sonalika.com\/morocco\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Become a Sonalika Dealer in Morocco | Join Now!","description":"Join Sonalika as a dealer in Morocco. Partner with us to distribute high-quality agricultural equipment. Apply now!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/","og_locale":"en_US","og_type":"article","og_title":"Become a Sonalika Dealer in Morocco | Join Now!","og_description":"Join Sonalika as a dealer in Morocco. Partner with us to distribute high-quality agricultural equipment. Apply now!","og_url":"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/","og_site_name":"Sonalika Morocco","article_modified_time":"2024-07-04T09:42:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/","url":"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/","name":"Become a Sonalika Dealer in Morocco | Join Now!","isPartOf":{"@id":"http:\/\/international.sonalika.com\/morocco\/#website"},"datePublished":"2020-09-09T05:32:45+00:00","dateModified":"2024-07-04T09:42:46+00:00","description":"Join Sonalika as a dealer in Morocco. Partner with us to distribute high-quality agricultural equipment. Apply now!","breadcrumb":{"@id":"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/international.sonalika.com\/morocco\/become-a-dealer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/international.sonalika.com\/morocco\/"},{"@type":"ListItem","position":2,"name":"Become A Dealer"}]},{"@type":"WebSite","@id":"http:\/\/international.sonalika.com\/morocco\/#website","url":"http:\/\/international.sonalika.com\/morocco\/","name":"Sonalika Morocco","description":"Tractor Portal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/international.sonalika.com\/morocco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/pages\/3277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/comments?post=3277"}],"version-history":[{"count":1,"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/pages\/3277\/revisions"}],"predecessor-version":[{"id":9158,"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/pages\/3277\/revisions\/9158"}],"wp:attachment":[{"href":"https:\/\/international.sonalika.com\/morocco\/wp-json\/wp\/v2\/media?parent=3277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}